{"id":5270,"date":"2018-05-23T11:00:38","date_gmt":"2018-05-23T10:00:38","guid":{"rendered":"https:\/\/palmadelrio.salesianos.edu\/colegio\/?page_id=5270"},"modified":"2024-05-08T09:24:19","modified_gmt":"2024-05-08T08:24:19","slug":"fpb_administrativo","status":"publish","type":"page","link":"https:\/\/palmadelrio.salesianos.edu\/colegio\/fpb_administrativo\/","title":{"rendered":"fpb_administrativo"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb admin_label=\u00bbCabecera Servicios Administrativos\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbServicios Administrativos\u00bb admin_label=\u00bbT\u00edtulo FPB Servicios Administrativos\u00bb module_class=\u00bbpagina-imagen-cabecera\u00bb _builder_version=\u00bb4.25.0&#8243; background_color=\u00bbrgba(255, 255, 255, 0)\u00bb background_image=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/wp-content\/uploads\/2017\/09\/fondo.jpg\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb background_layout=\u00bblight\u00bb global_colors_info=\u00bb{}\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbSaludo Inicial\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTexto Saludo Inicial\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Saludo Inicial<\/strong><\/h2>\n<p style=\"text-align: justify;\">Hola a todos\/as.<\/p>\n<p style=\"text-align: justify;\">En nuestra casa salesiana son muchas las personas que estamos detr\u00e1s de m\u00faltiples tareas, actividades e iniciativas (se pueden ver en esta p\u00e1gina y en nuestras redes sociales). Quisi\u00e9ramos destacar que es mucha la dedicaci\u00f3n, el cari\u00f1o y el coraz\u00f3n que se pone en cada proyecto o idea que nace de nuestra casa de Palma del R\u00edo. Buscamos hacer nuestro mundo m\u00e1s cercano, haciendo presente el sue\u00f1o de Don Bosco. Queremos que esta sea vuestra casa y form\u00e9is parte de esta gran \u201cFAMILIA\u201d. Por eso desde estas l\u00edneas, quisi\u00e9ramos agradeceros vuestra confianza y desearos a todos que teng\u00e1is un buen curso. Comunicaros de igual forma que estamos a vuestra disposici\u00f3n para cualquier duda o sugerencia que quer\u00e1is transmitirnos.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bbSaber Mas\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTexto Saber mas FPB\u00bb _builder_version=\u00bb4.25.0&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Saber m\u00e1s sobre Grado B\u00e1sico&#8230;<\/strong><\/h2>\n<p style=\"text-align: justify;\">La formaci\u00f3n profesional de grado b\u00e1sico es la etapa educativa en la que el alumnado se encuentra ante la posibilidad de continuar su formaci\u00f3n en un itinerario alternativo. En dicho itinerario ser\u00e1 capaz de asumir contenidos, madurar actitudes y desarrollar capacidades que le habiliten para el ejercicio laboral en un puesto de trabajo inmerso en un mercado laboral cada vez m\u00e1s exigente y demandante de buenos profesionales y mejores personas.<\/p>\n<p style=\"text-align: justify;\">Desde el Centro Educativo Salesiano \u00abSan Luis Rey\u00bb de Palma del R\u00edo se apuesta por esta etapa al ser protagonistas de la misma, personas que, por distintos motivos, tienen la necesidad de formarse como profesionales desde un prisma salesiano y demandan ayuda para realizar otros recorridos educativos.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bbDescripci\u00f3n del Ciclo\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTexto Descripcion del Ciclo\u00bb _builder_version=\u00bb4.25.0&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Descripci\u00f3n del ciclo<\/strong><\/h2>\n<p style=\"text-align: justify;\">Si te gusta el <strong>funcionamiento administrativo de una empresa<\/strong> y quieres aprenderlo de una manera totalmente pr\u00e1ctica, te ofrecemos la posibilidad de hacerlo con el curso de <strong>Formaci\u00f3n Profesional de Grado B\u00e1sico de Servicios Administrativos<\/strong>, en nuestro Centro Educativo Salesiano \u00abSan Luis Rey\u00bb de Palma del R\u00edo.<\/p>\n<p align=\"justify\">Este ciclo es de 2000 horas, son de dos cursos acad\u00e9micos de 1000 horas cada uno. Est\u00e1 organizado en m\u00f3dulos profesionales de duraci\u00f3n variable, constituidos por \u00e1reas de conocimiento te\u00f3rico-pr\u00e1ctico cuyo objeto es la adquisici\u00f3n de las competencias profesionales, personales y sociales y de las competencias de aprendizaje permanente a lo largo de la vida.<\/p>\n<p align=\"justify\">Al finalizar los estudios obtendr\u00e1s el t\u00edtulo Profesional B\u00e1sico correspondiente, con valor acad\u00e9mico y profesional y con validez en todo el territorio nacional. Te permitir\u00e1 el acceso a Ciclos Formativos de Grado Medio.<\/p>\n<p align=\"justify\">Adem\u00e1s, si lo aprendido despierta tu curiosidad por saber\u00a0 a\u00fan m\u00e1s, <strong>podr\u00e1s continuar con tus estudios<\/strong> en nuestro Centro, accediendo con la titulaci\u00f3n obtenida al <strong>Ciclo Formativo de Grado Medio de GESTI\u00d3N ADMINISTRATIVA<\/strong> y posteriormente al <strong>Ciclo Formativo de Grado Superior de ADMINISTRACI\u00d3N Y FINANZAS<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; admin_label=\u00bbIm\u00e1genes Descripci\u00f3n del Ciclo\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/IMG_7549-scaled.jpg\u00bb title_text=\u00bbIMG_7549&#8243; admin_label=\u00bbImagen Departamento Administrativo 1&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text admin_label=\u00bbTexto Departamento Recepci\u00f3n\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Departamento Recepci\u00f3n<\/h4>\n<p align=\"justify\">[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/IMG_7555-scaled.jpg\u00bb title_text=\u00bbIMG_7555&#8243; admin_label=\u00bbImagen Departamento Administrativo 2&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text admin_label=\u00bbTexto Departamento Contabilidad\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Departamento Contabilidad<\/h4>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bbPlan de Estudios\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbT\u00edtulo Plan de Estudios\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Plan de Estudios<\/h2>\n<p>[\/et_pb_text][et_pb_tabs admin_label=\u00bbPesta\u00f1as Cursos\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_tab title=\u00bbPrimer Curso\u00bb _builder_version=\u00bb4.16&#8243; body_font=\u00bb||||\u00bb body_line_height=\u00bb2em\u00bb tab_font=\u00bb||||\u00bb tab_line_height=\u00bb2em\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb body_line_height_tablet=\u00bb2em\u00bb body_line_height_phone=\u00bb2em\u00bb tab_line_height_tablet=\u00bb2em\u00bb tab_line_height_phone=\u00bb2em\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"60%\"><strong>M\u00d3DULO<\/strong><\/td>\n<td width=\"20%\"><strong>HORAS TOTALES<\/strong><\/td>\n<td width=\"20%\"><strong>HORAS SEMANALES<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Tratamiento inform\u00e1tico de datos<\/td>\n<td>224<\/td>\n<td>7<\/td>\n<\/tr>\n<tr>\n<td>T\u00e9cnicas administrativas b\u00e1sicas<\/td>\n<td>224<\/td>\n<td>7<\/td>\n<\/tr>\n<tr>\n<td>Atenci\u00f3n al Cliente<\/td>\n<td>64<\/td>\n<td>2<\/td>\n<\/tr>\n<tr>\n<td>Ciencias aplicadas I<\/td>\n<td>160<\/td>\n<td>5<\/td>\n<\/tr>\n<tr>\n<td>Comunicaci\u00f3n y sociedad I<\/td>\n<td>256<\/td>\n<td>8<\/td>\n<\/tr>\n<tr>\n<td>Tutor\u00eda<\/td>\n<td>32<\/td>\n<td>1<\/td>\n<\/tr>\n<tr>\n<td><strong>TOTALES<\/strong><\/td>\n<td><strong>960<\/strong><\/td>\n<td><strong>30<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_tab][et_pb_tab title=\u00bbSegundo curso\u00bb _builder_version=\u00bb4.16&#8243; body_font=\u00bb||||\u00bb body_line_height=\u00bb2em\u00bb tab_font=\u00bb||||\u00bb tab_line_height=\u00bb2em\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb body_line_height_tablet=\u00bb2em\u00bb body_line_height_phone=\u00bb2em\u00bb tab_line_height_tablet=\u00bb2em\u00bb tab_line_height_phone=\u00bb2em\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<table style=\"height: 254px;\">\n<tbody>\n<tr style=\"height: 47px;\">\n<td style=\"height: 47px; width: 434.267px;\"><strong>M\u00d3DULO<\/strong><\/td>\n<td style=\"height: 47px; width: 142.35px;\"><strong>HORAS TOTALES<\/strong><\/td>\n<td style=\"height: 47px; width: 142.333px;\"><strong>HORAS SEMANALES<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"height: 23px; width: 434.267px;\">Aplicaciones b\u00e1sicas de ofim\u00e1tica<\/td>\n<td style=\"height: 23px; width: 142.35px;\">182<\/td>\n<td style=\"height: 23px; width: 142.333px;\">7<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"height: 23px; width: 434.267px;\">Archivo y Comunicaci\u00f3n<\/td>\n<td style=\"height: 23px; width: 142.35px;\">130<\/td>\n<td style=\"height: 23px; width: 142.333px;\">5<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"height: 23px; width: 434.267px;\">Preparaci\u00f3n de pedidos y venta de productos<\/td>\n<td style=\"height: 23px; width: 142.35px;\">104<\/td>\n<td style=\"height: 23px; width: 142.333px;\">4<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"height: 23px; width: 434.267px;\">Ciencias aplicadas II<\/td>\n<td style=\"height: 23px; width: 142.35px;\">130<\/td>\n<td style=\"height: 23px; width: 142.333px;\">5<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"height: 23px; width: 434.267px;\">Comunicaci\u00f3n y sociedad II<\/td>\n<td style=\"height: 23px; width: 142.35px;\">182<\/td>\n<td style=\"height: 23px; width: 142.333px;\">7<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"height: 23px; width: 434.267px;\">Tutor\u00eda<\/td>\n<td style=\"height: 23px; width: 142.35px;\">26<\/td>\n<td style=\"height: 23px; width: 142.333px;\">1<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"height: 23px; width: 434.267px;\">U.F. Prevenci\u00f3n FPB<\/td>\n<td style=\"height: 23px; width: 142.35px;\">26<\/td>\n<td style=\"height: 23px; width: 142.333px;\">1<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"height: 23px; width: 434.267px;\">Formaci\u00f3n en centros de trabajo<\/td>\n<td style=\"height: 23px; width: 142.35px;\">260<\/td>\n<td style=\"height: 23px; width: 142.333px;\">0<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"height: 23px; width: 434.267px;\"><strong>TOTALES<\/strong><\/td>\n<td style=\"height: 23px; width: 142.35px;\"><strong>1040<\/strong><\/td>\n<td style=\"height: 23px; width: 142.333px;\"><strong>30<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_tab][\/et_pb_tabs][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bbAccede a FPB\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTexto Accede a FPB\u00bb _builder_version=\u00bb4.25.0&#8243; module_alignment=\u00bbleft\u00bb border_style_all=\u00bbsolid\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Acceso a FP de Grado B\u00e1sico<\/h2>\n<p style=\"text-align: justify;\">El\u00a0<strong>acceso<\/strong> a la Formaci\u00f3n Profesional de Grado B\u00e1sico requerir\u00e1 el cumplimiento simult\u00e1neo de las siguientes condiciones:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Tener cumplidos 15 a\u00f1os, o cumplirlos durante el a\u00f1o natural en curso, y no superar los 17 a\u00f1os de edad en el momento del acceso o durante el a\u00f1o natural en curso.<\/li>\n<li style=\"text-align: justify;\">Haber cursado 3\u00ba de ESO. Excepcionalmente se puede acceder si has cursado 2\u00ba de ESO.<\/li>\n<li style=\"text-align: justify;\">Haber propuesto el equipo docente a los padres, madres o tutores legales la incorporaci\u00f3n del alumno o alumna a un ciclo de Formaci\u00f3n Profesional de Grado B\u00e1sico.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bbPrepara tu futuro\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTexto Prepara tu futuro con nosotros\u00bb _builder_version=\u00bb4.16&#8243; module_alignment=\u00bbleft\u00bb border_style_all=\u00bbsolid\u00bb border_style=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Prepara tu futuro con nosotros<\/h2>\n<p style=\"text-align: justify;\">Si est\u00e1s interesado en estudiar este ciclo de formaci\u00f3n profesional b\u00e1sica con nosotros,\u00a0<strong>a partir de abril publicaremos toda la informaci\u00f3n al respecto<\/strong>. S\u00edguenos en nuestras\u00a0<strong>redes sociales<\/strong>\u00a0y te avisaremos cuando se abra el\u00a0<strong>proceso de pre-inscripci\u00f3n y matr\u00edcula.<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; admin_label=\u00bbCuadrados\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_cta title=\u00bbSalidas profesionales\u00bb admin_label=\u00bbSalidas Profesionales\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbAmatic SC||||\u00bb header_text_color=\u00bb#ffffff\u00bb header_font_size=\u00bb48&#8243; body_font=\u00bbAmatic SC||||\u00bb body_text_color=\u00bb#ffffff\u00bb body_font_size=\u00bb16&#8243; background_image=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/wp-content\/uploads\/2017\/09\/fondo.jpg\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb42&#8243; button_text_color=\u00bb#ffffff\u00bb button_border_width=\u00bb0&#8243; button_font=\u00bbAmatic SC|on|||\u00bb button_use_icon=\u00bboff\u00bb text_orientation=\u00bbleft\u00bb border_style=\u00bbsolid\u00bb saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]<\/p>\n<ul>\n<li class=\"ta-justify\">Auxiliar de oficina.<\/li>\n<li class=\"ta-justify\">Auxiliar de servicios generales.<\/li>\n<li class=\"ta-justify\">Auxiliar de archivo.<\/li>\n<li class=\"ta-justify\">Ordenanza.<\/li>\n<li class=\"ta-justify\">Auxiliar de informaci\u00f3n.<\/li>\n<li class=\"ta-justify\">Telefonista en servicios centrales de informaci\u00f3n.<\/li>\n<li class=\"ta-justify\">Clasificador y\/o repartidor de correspondencia.<\/li>\n<li class=\"ta-justify\">Grabador-verificador de datos.<\/li>\n<li class=\"ta-justify\">Auxiliar de digitalizaci\u00f3n.<\/li>\n<li class=\"ta-justify\">Operador documental.<\/li>\n<li class=\"ta-justify\">Auxiliar de venta.<\/li>\n<li class=\"ta-justify\">Auxiliar de dependiente de comercio<\/li>\n<li class=\"ta-justify\">Operador\/a de cobro o Cajero\/a.<\/li>\n<\/ul>\n<p>[\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_cta title=\u00bb\u00bfY qu\u00e9 puedo seguir estudiando?\u00bb admin_label=\u00bb\u00bfY qu\u00e9 puedo seguir estudiando?\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbAmatic SC||||\u00bb header_text_color=\u00bb#ffffff\u00bb header_font_size=\u00bb48&#8243; body_font=\u00bbAmatic SC||||\u00bb body_text_color=\u00bb#ffffff\u00bb body_font_size=\u00bb16&#8243; background_image=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/wp-content\/uploads\/2017\/09\/fondo.jpg\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb42&#8243; button_text_color=\u00bb#ffffff\u00bb button_border_width=\u00bb0&#8243; button_font=\u00bbAmatic SC|on|||\u00bb button_use_icon=\u00bboff\u00bb text_orientation=\u00bbleft\u00bb border_style_all=\u00bbsolid\u00bb border_style=\u00bbsolid\u00bb saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]<\/p>\n<ul>\n<li class=\"ta-justify\">Un ciclo formativo de grado medio (Este t\u00edtulo tendr\u00e1 preferencia para la admisi\u00f3n a todos los t\u00edtulos de grado medio de las familias profesionales de Administraci\u00f3n y Gesti\u00f3n, Comercio y Marketing, Textil, Confecci\u00f3n y Piel, Vidrio y cer\u00e1mica y Artes Gr\u00e1ficas)<\/li>\n<\/ul>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bb\u00bfC\u00f3mo puedo Saber mas sobre FPB?\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTexto Saber mas FPB\u00bb _builder_version=\u00bb4.25.0&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>\u00bfC\u00f3mo puedo saber m\u00e1s de la FP de Grado B\u00e1sico?<br \/><\/strong><\/h2>\n<p>Visitando el siguiente enlace de la Junta de Andaluc\u00eda: <a href=\"http:\/\/www.juntadeandalucia.es\/educacion\/portals\/web\/formacion-profesional-andaluza\/quiero-formarme\/ensenanzas\/fp-basica\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.juntadeandalucia.es\/educacion\/portals\/web\/formacion-profesional-andaluza\/quiero-formarme\/ensenanzas\/fp-basica<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bbActividades Realizadas en el Centro\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTexto Actividades del Centro\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 class=\"western\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: x-large;\"><b>Actividades Realizadas en el Centro<\/b><\/span><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h2><strong>D\u00eda de Don Bosco<br \/><\/strong><\/h2>\n<ul class=\"et_post_gallery clearfix\">\n\t\t\t\t\t<li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/1-FPB-RED.jpg\" title=\"1-FPB-RED\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/1-FPB-RED-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DonBosco-02.jpg\" title=\"DonBosco-02\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DonBosco-02-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DonBosco-21.jpg\" title=\"DonBosco-21\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DonBosco-21-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n<h2><strong>D\u00eda de Mar\u00eda Auxiliadora<br \/><\/strong><\/h2>\n<ul class=\"et_post_gallery clearfix\">\n\t\t\t\t\t<li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/MariaAuxiliadora-23.jpg\" title=\"MariaAuxiliadora-23\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/MariaAuxiliadora-23-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/MariaAuxiliadora-27.jpg\" title=\"MariaAuxiliadora-27\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/MariaAuxiliadora-27-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/MariaAuxiliadora-31.jpg\" title=\"MariaAuxiliadora-31\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/MariaAuxiliadora-31-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n<h2><strong>Adornando Clases y Pasillos para la Navidad<br \/><\/strong><\/h2>\n<ul class=\"et_post_gallery clearfix\">\n\t\t\t\t\t<li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DecorandoNavidad03.jpg\" title=\"DecorandoNavidad03\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DecorandoNavidad03-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DecorandoNavidad02.jpg\" title=\"DecorandoNavidad02\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DecorandoNavidad02-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DecorandoNavidad01.jpg\" title=\"DecorandoNavidad01\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DecorandoNavidad01-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n<h2><strong>Din\u00e1micas de Clase<br \/><\/strong><\/h2>\n<ul class=\"et_post_gallery clearfix\">\n\t\t\t\t\t<li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DinamicaFPB-01.jpg\" title=\"DinamicaFPB-01\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DinamicaFPB-01-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DinamicaFPB-06.jpg\" title=\"DinamicaFPB-06\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DinamicaFPB-06-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DinamicaFPB-08.jpg\" title=\"DinamicaFPB-08\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/DinamicaFPB-08-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n<h2><strong>Sesi\u00f3n Fotogr\u00e1fica de Estudio<br \/><\/strong><\/h2>\n<ul class=\"et_post_gallery clearfix\">\n\t\t\t\t\t<li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/FPB19-20-169.jpg\" title=\"FPB19-20-169\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/FPB19-20-169-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/FPB19-20-057-scaled.jpg\" title=\"FPB19-20-057\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/FPB19-20-057-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li><li class=\"et_gallery_item et_pb_gallery_image\">\n\t\t\t\t\t\t<a href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/FPB19-20-187.jpg\" title=\"FPB19-20-187\">\n\t\t\t\t\t\t\t<span class=\"et_portfolio_image\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/06\/FPB19-20-187-400x284.jpg\" class=\"attachment-et-pb-portfolio-image size-et-pb-portfolio-image\" alt=\"\" \/>\n\t\t\t\t\t\t\t\t<span class=\"et_overlay\"><\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saludo Inicial Hola a todos\/as. En nuestra casa salesiana son muchas las personas que estamos detr\u00e1s de m\u00faltiples tareas, actividades e iniciativas (se pueden ver en esta p\u00e1gina y en nuestras redes sociales). Quisi\u00e9ramos destacar que es mucha la dedicaci\u00f3n, el cari\u00f1o y el coraz\u00f3n que se pone en cada proyecto o idea que nace [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-5270","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>fpb_administrativo - Colegio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/fpb_administrativo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"fpb_administrativo - Colegio\" \/>\n<meta property=\"og:description\" content=\"Saludo Inicial Hola a todos\/as. En nuestra casa salesiana son muchas las personas que estamos detr\u00e1s de m\u00faltiples tareas, actividades e iniciativas (se pueden ver en esta p\u00e1gina y en nuestras redes sociales). Quisi\u00e9ramos destacar que es mucha la dedicaci\u00f3n, el cari\u00f1o y el coraz\u00f3n que se pone en cada proyecto o idea que nace [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/fpb_administrativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T08:24:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/fpb_administrativo\\\/\",\"url\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/fpb_administrativo\\\/\",\"name\":\"fpb_administrativo - Colegio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/#website\"},\"datePublished\":\"2018-05-23T10:00:38+00:00\",\"dateModified\":\"2024-05-08T08:24:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/fpb_administrativo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/fpb_administrativo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/fpb_administrativo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"fpb_administrativo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio\",\"description\":\"P\u00e1gina oficial Salesianos Palma del R\u00edo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"fpb_administrativo - Colegio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palmadelrio.salesianos.edu\/colegio\/fpb_administrativo\/","og_locale":"es_ES","og_type":"article","og_title":"fpb_administrativo - Colegio","og_description":"Saludo Inicial Hola a todos\/as. En nuestra casa salesiana son muchas las personas que estamos detr\u00e1s de m\u00faltiples tareas, actividades e iniciativas (se pueden ver en esta p\u00e1gina y en nuestras redes sociales). Quisi\u00e9ramos destacar que es mucha la dedicaci\u00f3n, el cari\u00f1o y el coraz\u00f3n que se pone en cada proyecto o idea que nace [&hellip;]","og_url":"https:\/\/palmadelrio.salesianos.edu\/colegio\/fpb_administrativo\/","og_site_name":"Colegio","article_modified_time":"2024-05-08T08:24:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/palmadelrio.salesianos.edu\/colegio\/fpb_administrativo\/","url":"https:\/\/palmadelrio.salesianos.edu\/colegio\/fpb_administrativo\/","name":"fpb_administrativo - Colegio","isPartOf":{"@id":"https:\/\/palmadelrio.salesianos.edu\/colegio\/#website"},"datePublished":"2018-05-23T10:00:38+00:00","dateModified":"2024-05-08T08:24:19+00:00","breadcrumb":{"@id":"https:\/\/palmadelrio.salesianos.edu\/colegio\/fpb_administrativo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/palmadelrio.salesianos.edu\/colegio\/fpb_administrativo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/palmadelrio.salesianos.edu\/colegio\/fpb_administrativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/palmadelrio.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"fpb_administrativo"}]},{"@type":"WebSite","@id":"https:\/\/palmadelrio.salesianos.edu\/colegio\/#website","url":"https:\/\/palmadelrio.salesianos.edu\/colegio\/","name":"Colegio","description":"P\u00e1gina oficial Salesianos Palma del R\u00edo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palmadelrio.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/5270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=5270"}],"version-history":[{"count":23,"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/5270\/revisions"}],"predecessor-version":[{"id":6045,"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/5270\/revisions\/6045"}],"wp:attachment":[{"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=5270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}