{"id":6337,"date":"2025-05-27T08:59:20","date_gmt":"2025-05-27T07:59:20","guid":{"rendered":"https:\/\/palmadelrio.salesianos.edu\/colegio\/?page_id=6337"},"modified":"2026-06-08T08:17:06","modified_gmt":"2026-06-08T07:17:06","slug":"admisiones-ccff","status":"publish","type":"page","link":"https:\/\/palmadelrio.salesianos.edu\/colegio\/admisiones-ccff\/","title":{"rendered":"Admisiones CCFF"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; transparent_background=\u00bboff\u00bb make_fullwidth=\u00bboff\u00bb use_custom_width=\u00bboff\u00bb width_unit=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_slider show_image_video_mobile=\u00bbon\u00bb disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbPortada (Deslizador)\u00bb _builder_version=\u00bb4.27.6&#8243; body_text_color=\u00bb#E02B20&#8243; custom_padding=\u00bb||54px|||\u00bb custom_padding_tablet=\u00bb|||\u00bb custom_padding_phone=\u00bb|||\u00bb auto=\u00bbon\u00bb box_shadow_style=\u00bbpreset1&#8243; box_shadow_horizontal=\u00bb15px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb show_inner_shadow=\u00bbon\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][et_pb_slide button_text=\u00bbSolicitar Info FP\u00bb button_link=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/contactar-fp\/\u00bb url_new_window=\u00bbon\u00bb use_bg_overlay=\u00bbon\u00bb bg_overlay_color=\u00bbrgba(255,255,255,0.24)\u00bb _builder_version=\u00bb4.27.6&#8243; header_text_color=\u00bb#E02B20&#8243; header_font_size=\u00bb49px\u00bb body_font=\u00bbCalligraffitti||||\u00bb body_font_size=\u00bb34px\u00bb body_line_height=\u00bb1.1em\u00bb background_color=\u00bbrgba(255,255,255,0)\u00bb background_enable_color=\u00bbon\u00bb background_image=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/06\/BANNER-CENTRAL-FP-mayo-26-N4-scaled.jpg\u00bb background_enable_image=\u00bbon\u00bb background_blend=\u00bboverlay\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb30px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#bb0020&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#ffffff\u00bb button_border_radius=\u00bb3px\u00bb button_font=\u00bbAmatic SC|on|||\u00bb button_icon_placement=\u00bbright\u00bb button_alignment=\u00bbright\u00bb overflow-x=\u00bbhidden\u00bb overflow-y=\u00bbhidden\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb sticky_transition=\u00bbon\u00bb][\/et_pb_slide][\/et_pb_fullwidth_slider][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; background_color=\u00bbrgba(255,255,255,0.55)\u00bb background_enable_image=\u00bboff\u00bb background_blend=\u00bbsoft-light\u00bb module_alignment=\u00bbcenter\u00bb custom_padding=\u00bb50px|0px|70px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbT\u00edtulo\u00bb _builder_version=\u00bb4.27.4&#8243; module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb0px|auto|0px|326px||\u00bb custom_padding=\u00bb0px||0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbEscolarizaci\u00f3n Curso\u00bb _builder_version=\u00bb4.27.6&#8243; text_font=\u00bb||||||||\u00bb text_text_color=\u00bb#e02b20&#8243; text_font_size=\u00bb27px\u00bb custom_margin=\u00bb0px||0px\u00bb custom_padding=\u00bb0px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #dc001b; font-size: 45px;\">Escolarizaci\u00f3n 2026-2027<\/span><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbFormaci\u00f3n Profesional\u00bb _builder_version=\u00bb4.27.4&#8243; text_font=\u00bb||||||||\u00bb text_text_color=\u00bb#e02b20&#8243; text_font_size=\u00bb27px\u00bb custom_margin=\u00bb0px||12px|||\u00bb custom_padding=\u00bb0px||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong>FORMACI\u00d3N PROFESIONAL<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb#calendario1&#8243; button_text=\u00bbCalendario de Escolarizaci\u00f3n\u00bb button_alignment=\u00bbcenter\u00bb disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbCalendario\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_divider _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.4&#8243; custom_margin=\u00bb0px||0px\u00bb custom_padding=\u00bb0px||0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbIntroducci\u00f3n General\u00bb _builder_version=\u00bb4.27.4&#8243; text_font_size=\u00bb18px\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\"><strong><em>CICLOS FORMATIVOS DE GRADO B\u00c1SICO, MEDIO Y SUPERIOR.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Nuestro centro cuenta con un <strong>atractivo proyecto de formaci\u00f3n profesional<\/strong> en el que destacan el\u00a0<strong>ambiente educativo<\/strong>, las metodolog\u00edas activas empleadas, los acuerdos con <strong>empresas del sector<\/strong>, la oferta de\u00a0<strong>Formaci\u00f3n Profesional, con dos ciclos de grado b\u00e1sico, cuatro de grado medio y dos de grado superior<\/strong> y la posibilidad de cursar el periodo de pr\u00e1cticas en empresas ubicadas en el extranjero a trav\u00e9s de los proyectos <strong>Erasmus+<\/strong>.<\/p>\n<p style=\"text-align: justify;\">El<strong> Colegio Salesiano de Palma del R\u00edo <\/strong>es un centro<strong> concertado en todas sus etapas<\/strong><strong>. <\/strong><\/p>\n<p>[\/et_pb_text][et_pb_divider _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_cta title=\u00bbConoce nuestra oferta formativa de FP\u00bb button_url=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/colegio\/ciclos-formativos\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbM\u00e1s Informaci\u00f3n\u00bb disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbOferta Formativa FP\u00bb _builder_version=\u00bb4.27.4&#8243; background_image=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/05\/administracion_1-1.jpg\u00bb background_repeat=\u00bbrepeat\u00bb background_blend=\u00bbsoft-light\u00bb link_option_url_new_window=\u00bbon\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb box_shadow_style=\u00bbpreset3&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_cta][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbADMISI\u00d3N DE SOLICITUDES \u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbAdmisi\u00f3n de Solicitudes\u00bb _builder_version=\u00bb4.27.4&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La informaci\u00f3n necesaria para este proceso de solicitud estar\u00e1 disponible en la siguiente p\u00e1gina:<\/span><i><span style=\"font-weight: 400;\">\u00a0<\/span><\/i><i><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/escolarizacion\/formacion-profesional\" target=\"_blank\" rel=\"noopener\">Portal de Escolarizaci\u00f3n<\/a>\u00a0<\/span><\/i><\/p>\n<p style=\"text-align: justify;\"><em>Las solicitudes pueden presentarse mediante dos modalidades:<br \/><\/em><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 16px;\">1 &#8211; PRESENTACI\u00d3N TELEM\u00c1TICA | <\/strong><span style=\"font-size: 16px;\">\u00a0La presentaci\u00f3n telem\u00e1tica puede hacerse de distintos modos: mediante certificado digital o firma electr\u00f3nica, mediante identificaci\u00f3n a trav\u00e9s del sistema Cl@ve o mediante una clave iAnde, que podr\u00e1 obtener registr\u00e1ndose en la Secretar\u00eda Virtual de la Consejer\u00eda de Educaci\u00f3n y Deporte, para lo que necesitar\u00e1 su DNI y n\u00famero de m\u00f3vil. Tambi\u00e9n es posible cumplimentar un formulario online, que posteriormente deber\u00e1 llevar al centro elegido.<\/span><\/p>\n<p style=\"text-align: justify;\">En la solicitud se debe seleccionar como centro educativo: <strong>14005213 C.D.P. San Luis Rey, Palma del R\u00edo (C\u00f3rdoba) <\/strong>y disponer de la <strong>nota media de acceso para su cumplimentaci\u00f3n<\/strong>.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>Enlace directo a la solicitud de grado b\u00e1sico:<\/strong> <a href=\"https:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/265\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/265\/&amp;source=gmail&amp;ust=1750143177787000&amp;usg=AOvVaw1YmxRdgyDeUVSVjUreffW4\">https:\/\/www.juntadeandalucia.<wbr \/>es\/educacion\/<wbr \/>secretariavirtual\/<wbr \/>accesoTramite\/265\/<\/a><\/li>\n<li style=\"text-align: justify;\"><strong>Enlace directo a la solicitud de grado medio:<\/strong> <a href=\"https:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/308\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/308\/&amp;source=gmail&amp;ust=1750143177787000&amp;usg=AOvVaw0zZ0VMbu_ounzXQgeiHXJf\">https:\/\/www.juntadeandalucia.<wbr \/>es\/educacion\/<wbr \/>secretariavirtual\/<wbr \/>accesoTramite\/308\/<\/a><\/li>\n<li style=\"text-align: justify;\"><strong>Enlace directo a la solicitud de grado superior:<\/strong> <a href=\"https:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/317\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/317\/&amp;source=gmail&amp;ust=1750143177787000&amp;usg=AOvVaw1MMPnzE6W2acdAg8lR1dmp\">https:\/\/www.juntadeandalucia.<wbr \/>es\/educacion\/<wbr \/>secretariavirtual\/<wbr \/>accesoTramite\/317\/<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 16px;\">2 &#8211; EN SECRETAR\u00cdA<\/strong><span style=\"font-size: 16px;\"> | Las personas que lo prefieran podr\u00e1n presentar la solicitud de manera presencial.\u00a0<\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>HORARIO DE ATENCI\u00d3N | <\/strong>De Lunes a Viernes en horario de 10:00 h a 13:00 h.\u00a0<strong><br \/><\/strong><\/li>\n<li style=\"text-align: justify;\"><strong>EMAIL<\/strong> | <a href=\"mailto:alumnado@palmadelrio.salesianos.edu\">alumnado@palmadelrio.salesianos.edu<\/a><\/li>\n<li style=\"text-align: justify;\"><strong>TEL\u00c9FONO | <\/strong><a href=\"tel:\/\/957710792\">957 710 792<\/a><span style=\"font-size: 16px;\">\u00a0<\/span><\/li>\n<\/ul>\n<h4>\u00a0<\/h4>\n<h3 style=\"text-align: justify;\"><strong>Para entregar en Secretar\u00eda:<\/strong><\/h3>\n<ul>\n<li><strong>Solicitud cumplimentada. Original y copia.<\/strong><\/li>\n<li><strong>Fotocopia del DNI de la persona solicitante.<\/strong><\/li>\n<\/ul>\n<p>[\/et_pb_blurb][et_pb_button button_url=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/05\/ANEXO-I-ADMISION-GRADO-BASICO.pdf\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbImpreso de solicitud Grado B\u00e1sico\u00bb button_alignment=\u00bbcenter\u00bb disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbImpreso Grado B\u00e1sico\u00bb _builder_version=\u00bb4.27.4&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_icon=\u00bb&#xe058;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb box_shadow_style=\u00bbpreset2&#8243; button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#cc1c1c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#cc1c1c\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/05\/ANEXO-II-ADMISION-GM.pdf\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbImpreso de solicitud Grado Medio\u00bb button_alignment=\u00bbcenter\u00bb disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbImpreso Grado Medio\u00bb _builder_version=\u00bb4.27.4&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_icon=\u00bb&#xe058;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb box_shadow_style=\u00bbpreset2&#8243; button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#cc1c1c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#cc1c1c\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/05\/ANEXO-III-ADMISION-GS.pdf\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbImpreso de solicitud Grado Superior\u00bb button_alignment=\u00bbcenter\u00bb disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbImpreso Grado Superior\u00bb _builder_version=\u00bb4.27.4&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_icon=\u00bb&#xe058;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb box_shadow_style=\u00bbpreset2&#8243; button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#cc1c1c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#cc1c1c\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/05\/ANEXO-IV-ADMISION-2o-CURSO-GM-y-GS.pdf\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbImpreso de solicitud 2\u00ba Grado Medio y Superior\u00bb button_alignment=\u00bbcenter\u00bb disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbImpreso 2\u00ba Grado Medio y Superior\u00bb _builder_version=\u00bb4.27.4&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_icon=\u00bb&#xe058;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb box_shadow_style=\u00bbpreset2&#8243; button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#cc1c1c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#cc1c1c\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb71px\u00bb custom_padding=\u00bb||14px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbT\u00edtulo Fechas Importantes 1\u00ba Curso\u00bb _builder_version=\u00bb4.27.4&#8243; text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|300|||||||\u00bb header_2_font_size=\u00bb30px\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Fechas importantes en el proceso de escolarizaci\u00f3n 1\u00ba Curso de Grado B\u00e1sico, Medio y Superior<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbcalendario1&#8243; _builder_version=\u00bb4.27.4&#8243; custom_margin=\u00bb|||\u00bb custom_padding=\u00bb0px|||\u00bb custom_padding_tablet=\u00bb||0px|\u00bb custom_padding_phone=\u00bb||0px|\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbPRESENTACI\u00d3N DE SOLICITUDES | del 15 al 30 de Junio de 2026&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbPresentaci\u00f3n Solicitudes\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Presentaci\u00f3n de personas solicitantes de primer curso del 15 al 30 de Junio de 2026.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbRELACI\u00d3N PROVISIONAL | 2 de julio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbRelaci\u00f3n Provisional\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Relaci\u00f3n provisional de personas solicitantes de primer curso. Se publicar\u00e1 en el tabl\u00f3n de anuncios del hall del Colegio.<em><br \/><\/em><\/p>\n<p style=\"text-align: justify;\">A partir de esa fecha, <strong>se abrir\u00e1 un plazo de 4 d\u00edas<\/strong>\u00a0para la presentaci\u00f3n de <strong>alegaciones <\/strong>(desde el viernes 3 hasta el lunes 6 de julio).<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbRELACI\u00d3N DEFINITIVA | 9 de julio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbRelaci\u00f3n Definitiva\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Se publicar\u00e1 relaci\u00f3n definitiva de personas solicitantes de primer curso.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb1\u00aa ADJUDICACI\u00d3N| 9 de julio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bb1\u00aa Adjudicaci\u00f3n\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Primera adjudicaci\u00f3n de primer curso.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbMATRICULACI\u00d3N | Del 10 al 15 de julio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbMatriculaci\u00f3n\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: justify;\">Matriculaci\u00f3n o reserva de personas admitidas en la 1\u00aa adjudicaci\u00f3n.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb2\u00aa ADJUDICACI\u00d3N| 20 de julio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bb2\u00aa Adjudicaci\u00f3n\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Segunda adjudicaci\u00f3n de primer curso.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbMATRICULACI\u00d3N | Del 21 al 23 de julio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbMatriculaci\u00f3n\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: justify;\">Matriculaci\u00f3n o reserva de personas admitidas en la 2\u00aa adjudicaci\u00f3n.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||25px\u00bb custom_padding_tablet=\u00bb|||0px\u00bb custom_padding_phone=\u00bb|||0px\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbLISTAS DE ESPERA | ORDINARIO\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbRelaci\u00f3n Provisional Sep\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Desde el 1 de septiembre hasta el 15 de octubre\/ M\u00e1ximo 15 de noviembre.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>NOTA ACLARATORIA<\/strong><\/li>\n<\/ul>\n<p style=\"padding-left: 40px; text-align: justify;\">Agotadas las listas de espera, y dentro del plazo del 1 de septiembre hasta el 15 de Octubre, los centros docentes que dispongan de plazas escolares vacantes las ofrecer\u00e1n a las personas interesadas que cumplan los requisitos de acceso, siendo adjudicadas por Servicios Centrales. Pudiendo ampliar este plazo hasta el 15 de noviembre por parte de los centros previa publicaci\u00f3n.<\/p>\n<p>[\/et_pb_blurb][et_pb_divider disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.27.4&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><em>En nuestra casa, los\u00a0<strong>Salesianos<\/strong>\u00a0estamos presentes y\u00a0<strong>acompa\u00f1amos a grupos, equipos y personas<\/strong>\u00a0creyentes que son la base de una\u00a0<strong>comunidad cristiana de referencia<\/strong>\u00a0que hace posible la labor educativa y evangelizadora de nuestros proyectos y ambientes propios.<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb71px\u00bb custom_padding=\u00bb||14px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbT\u00edtulo Fechas Importantes 2\u00ba Curso\u00bb _builder_version=\u00bb4.27.4&#8243; text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|300|||||||\u00bb header_2_font_size=\u00bb30px\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Fechas importantes en el proceso de escolarizaci\u00f3n 2\u00ba Curso de Grado Medio y Superior<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbcalendario2&#8243; _builder_version=\u00bb4.27.4&#8243; custom_margin=\u00bb|||\u00bb custom_padding=\u00bb0px|||\u00bb custom_padding_tablet=\u00bb||0px|\u00bb custom_padding_phone=\u00bb||0px|\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbPRESENTACI\u00d3N DE SOLICITUDES | del 25 al 30 de Junio de 2026&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbPresentaci\u00f3n Solicitudes\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Presentaci\u00f3n de personas solicitantes de segundo curso del 25 al 30 de Junio de 2026.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbRELACI\u00d3N PROVISIONAL | 2 de julio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbRelaci\u00f3n Provisional\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Relaci\u00f3n provisional de personas solicitantes de segundo curso. Se publicar\u00e1 en el tabl\u00f3n de anuncios del hall del Colegio.<em><br \/><\/em><\/p>\n<p style=\"text-align: justify;\">A partir de esa fecha, <strong>se abrir\u00e1 un plazo de 4 d\u00edas<\/strong>\u00a0para la presentaci\u00f3n de <strong>alegaciones <\/strong>(desde el viernes 3 hasta el lunes 6 de julio).<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbRELACI\u00d3N DEFINITIVA | 15 de julio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbRelaci\u00f3n Definitiva\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Se publicar\u00e1 relaci\u00f3n definitiva de personas solicitantes de segundo curso.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbADJUDICACI\u00d3N| 15 de julio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbAdjudicaci\u00f3n\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Adjudicaci\u00f3n de segundo curso.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbMATRICULACI\u00d3N | Del 16 al 21 de julio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbMatriculaci\u00f3n\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Matriculaci\u00f3n de personas admitidas en la adjudicaci\u00f3n.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||25px\u00bb custom_padding_tablet=\u00bb|||0px\u00bb custom_padding_phone=\u00bb|||0px\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbLISTAS DE ESPERA | ORDINARIO\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb admin_label=\u00bbRelaci\u00f3n Provisional Sep\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Desde el 1 de septiembre hasta el 15 de octubre.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>NOTA ACLARATORIA<\/strong><\/li>\n<\/ul>\n<p style=\"padding-left: 40px; text-align: justify;\">Agotadas las listas de espera, y dentro del plazo del 1 de septiembre hasta el 15 de Octubre, los centros docentes que dispongan de plazas escolares vacantes las ofrecer\u00e1n a las personas interesadas que cumplan los requisitos de acceso.<\/p>\n<p>[\/et_pb_blurb][et_pb_divider disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.27.4&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><em>En nuestra casa, los\u00a0<strong>Salesianos<\/strong>\u00a0estamos presentes y\u00a0<strong>acompa\u00f1amos a grupos, equipos y personas<\/strong>\u00a0creyentes que son la base de una\u00a0<strong>comunidad cristiana de referencia<\/strong>\u00a0que hace posible la labor educativa y evangelizadora de nuestros proyectos y ambientes propios.<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.27.4&#8243; custom_margin=\u00bb0px||0px\u00bb custom_padding=\u00bb0px||0px\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_divider divider_style=\u00bbdashed\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb30px|40px|30px|40px\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_contact_form email=\u00bbalumnado@palmadelrio.salesianos.edu\u00bb title=\u00bb\u00bfAlguna duda sobre el procedimiento de admisi\u00f3n? Te ayudamos.\u00bb custom_message=\u00bb%%name%% ha enviado un mensaje solicitando informaci\u00f3n sobre PROCEDIMIENTO DE ADMISI\u00d3N CURSO 2025-26 (https:\/\/palmadelrio.salesianos.edu\/colegio\/admisiones-centro\/):||et_pb_line_break_holder||||et_pb_line_break_holder||&#8212;&#8212;||et_pb_line_break_holder||%%message%%||et_pb_line_break_holder||&#8212;&#8212;||et_pb_line_break_holder||||et_pb_line_break_holder||Puedes responder a este correo directamente salvo que te lo hayan REENVIADO. En ese caso, tendr\u00e1s que redactar un NUEVO CORREO con la respuesta y enviarlo a %%email%%.||et_pb_line_break_holder||||et_pb_line_break_holder||Para cualquier problema o sugerencia sobre el sistema de formularios de la web env\u00eda un correo a alumnado@palmadelrio.salesianos.edu\u00bb success_message=\u00bbGracias por interesarte en nuestro centro. Nos pondremos en contacto contigo lo antes posible.\u00bb admin_label=\u00bbFormulario de Dudas\u00bb module_id=\u00bbet_pb_contact_form_0&#8243; _builder_version=\u00bb4.27.4&#8243; _unique_id=\u00bbd55d3b38-4e63-44d6-8217-c0926e297858&#8243; title_level=\u00bbh2&#8243; title_font=\u00bbLato|300|||||||\u00bb title_font_size=\u00bb30px\u00bb title_line_height=\u00bb1.2em\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#e02b20&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_contact_field field_id=\u00bbName\u00bb field_title=\u00bbNombre\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbEmail\u00bb field_title=\u00bbDirecci\u00f3n de correo electr\u00f3nico\u00bb field_type=\u00bbemail\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbMessage\u00bb field_title=\u00bbMensaje\u00bb field_type=\u00bbtext\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbPrivacidad\u00bb field_title=\u00bb \u00bb field_type=\u00bbcheckbox\u00bb checkbox_options=\u00bb%91{%22value%22:%22 Acepto la pol\u00edtica de privacidad del sitio.%22,%22checked%22:0,%22dragID%22:-1}%93&#8243; fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb87px|0px|25.59375px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; text_font=\u00bb|300|||||||\u00bb text_font_size=\u00bb36px\u00bb header_2_font=\u00bbLato|300|||||||\u00bb header_2_font_size=\u00bb49px\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>\u00a1Gracias por su inter\u00e9s en nuestro centro!<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong>M\u00c1S INFORMACI\u00d3N: <\/strong><a href=\"https:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/escolarizacion\/formacion-profesional\" target=\"_blank\" rel=\"noopener noreferrer\">Escolarizaci\u00f3n curso 2026\/27<\/a> <em>(Fuente: Consejer\u00eda de Educaci\u00f3n. Junta de Andaluc\u00eda)<\/em><\/p>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/malaga.salesianos.edu\/politica-de-privacidad\/#privacidadmatriculacion\">*Protecci\u00f3n de datos sobre el proceso de matriculaciones<\/a>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escolarizaci\u00f3n 2026-2027FORMACI\u00d3N PROFESIONALCICLOS FORMATIVOS DE GRADO B\u00c1SICO, MEDIO Y SUPERIOR. Nuestro centro cuenta con un atractivo proyecto de formaci\u00f3n profesional en el que destacan el\u00a0ambiente educativo, las metodolog\u00edas activas empleadas, los acuerdos con empresas del sector, la oferta de\u00a0Formaci\u00f3n Profesional, con dos ciclos de grado b\u00e1sico, cuatro de grado medio y dos de grado superior [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-6337","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Admisiones CCFF - Colegio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/admisiones-ccff\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Admisiones CCFF - Colegio\" \/>\n<meta property=\"og:description\" content=\"Escolarizaci\u00f3n 2026-2027FORMACI\u00d3N PROFESIONALCICLOS FORMATIVOS DE GRADO B\u00c1SICO, MEDIO Y SUPERIOR. Nuestro centro cuenta con un atractivo proyecto de formaci\u00f3n profesional en el que destacan el\u00a0ambiente educativo, las metodolog\u00edas activas empleadas, los acuerdos con empresas del sector, la oferta de\u00a0Formaci\u00f3n Profesional, con dos ciclos de grado b\u00e1sico, cuatro de grado medio y dos de grado superior [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palmadelrio.salesianos.edu\/colegio\/admisiones-ccff\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T07:17:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/admisiones-ccff\\\/\",\"url\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/admisiones-ccff\\\/\",\"name\":\"Admisiones CCFF - Colegio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/#website\"},\"datePublished\":\"2025-05-27T07:59:20+00:00\",\"dateModified\":\"2026-06-08T07:17:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/admisiones-ccff\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/admisiones-ccff\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/admisiones-ccff\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Admisiones CCFF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio\",\"description\":\"P\u00e1gina oficial Salesianos Palma del R\u00edo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Admisiones CCFF - Colegio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palmadelrio.salesianos.edu\/colegio\/admisiones-ccff\/","og_locale":"es_ES","og_type":"article","og_title":"Admisiones CCFF - Colegio","og_description":"Escolarizaci\u00f3n 2026-2027FORMACI\u00d3N PROFESIONALCICLOS FORMATIVOS DE GRADO B\u00c1SICO, MEDIO Y SUPERIOR. Nuestro centro cuenta con un atractivo proyecto de formaci\u00f3n profesional en el que destacan el\u00a0ambiente educativo, las metodolog\u00edas activas empleadas, los acuerdos con empresas del sector, la oferta de\u00a0Formaci\u00f3n Profesional, con dos ciclos de grado b\u00e1sico, cuatro de grado medio y dos de grado superior [&hellip;]","og_url":"https:\/\/palmadelrio.salesianos.edu\/colegio\/admisiones-ccff\/","og_site_name":"Colegio","article_modified_time":"2026-06-08T07:17:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/palmadelrio.salesianos.edu\/colegio\/admisiones-ccff\/","url":"https:\/\/palmadelrio.salesianos.edu\/colegio\/admisiones-ccff\/","name":"Admisiones CCFF - Colegio","isPartOf":{"@id":"https:\/\/palmadelrio.salesianos.edu\/colegio\/#website"},"datePublished":"2025-05-27T07:59:20+00:00","dateModified":"2026-06-08T07:17:06+00:00","breadcrumb":{"@id":"https:\/\/palmadelrio.salesianos.edu\/colegio\/admisiones-ccff\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/palmadelrio.salesianos.edu\/colegio\/admisiones-ccff\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/palmadelrio.salesianos.edu\/colegio\/admisiones-ccff\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/palmadelrio.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Admisiones CCFF"}]},{"@type":"WebSite","@id":"https:\/\/palmadelrio.salesianos.edu\/colegio\/#website","url":"https:\/\/palmadelrio.salesianos.edu\/colegio\/","name":"Colegio","description":"P\u00e1gina oficial Salesianos Palma del R\u00edo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palmadelrio.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/6337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=6337"}],"version-history":[{"count":92,"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/6337\/revisions"}],"predecessor-version":[{"id":6630,"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/6337\/revisions\/6630"}],"wp:attachment":[{"href":"https:\/\/palmadelrio.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=6337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}