{"id":4164,"date":"2018-01-18T12:30:14","date_gmt":"2018-01-18T11:30:14","guid":{"rendered":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/26\/presentacion-reliquias-de-don-bosco\/"},"modified":"2018-01-26T12:36:36","modified_gmt":"2018-01-26T11:36:36","slug":"presentacion-reliquias-de-don-bosco","status":"publish","type":"post","link":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/","title":{"rendered":"Presentaci\u00f3n reliquias de Don Bosco"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section bb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb specialty=\u00bboff\u00bb][et_pb_fullwidth_image _builder_version=\u00bb3.0.89&#8243; src=\u00bbhttps:\/\/palmadelrio.salesianos.edu\/wp-content\/uploads\/2018\/01\/3.jpg\u00bb show_in_lightbox=\u00bboff\u00bb url_new_window=\u00bboff\u00bb use_overlay=\u00bboff\u00bb border_style=\u00bbsolid\u00bb animation=\u00bbleft\u00bb animation_direction=\u00bbleft\u00bb border_style_all=\u00bbsolid\u00bb \/][\/et_pb_section][et_pb_section bb_built=\u00bb1&#8243; fullwidth=\u00bboff\u00bb specialty=\u00bboff\u00bb transparent_background=\u00bboff\u00bb allow_player_pause=\u00bboff\u00bb inner_shadow=\u00bboff\u00bb parallax=\u00bboff\u00bb parallax_method=\u00bboff\u00bb custom_padding=\u00bb-4%|||\u00bb make_fullwidth=\u00bboff\u00bb use_custom_width=\u00bboff\u00bb width_unit=\u00bbon\u00bb make_equal=\u00bboff\u00bb use_custom_gutter=\u00bboff\u00bb module_class=\u00bbpagina-seccion-contenido\u00bb][et_pb_row make_fullwidth=\u00bboff\u00bb use_custom_width=\u00bboff\u00bb width_unit=\u00bbon\u00bb use_custom_gutter=\u00bboff\u00bb allow_player_pause=\u00bboff\u00bb parallax=\u00bboff\u00bb parallax_method=\u00bboff\u00bb make_equal=\u00bboff\u00bb parallax_1=\u00bboff\u00bb parallax_method_1=\u00bboff\u00bb module_class=\u00bbpagina-texto\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb background_size=\u00bbinitial\u00bb][et_pb_column type=\u00bb4_4&#8243;][et_pb_text background_layout=\u00bblight\u00bb border_style=\u00bbsolid\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb background_size=\u00bbinitial\u00bb _builder_version=\u00bb3.0.89&#8243; border_style_all=\u00bbsolid\u00bb]<\/p>\n<p>Nuestro sacerdote Don Fidel ha presentado hoy la reliquia de Don Bosco que tenemos en el colegio a nuestros alumnos de primero de ciclos formativos, destacando tambi\u00e9n algunos aspectos llamativos de su vida.<\/p>\n<p>Esta tutor\u00eda es una de las actividades que se est\u00e1n llevando a cabo con motivo de la Festividad del Mes de Don Bosco.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb3.0.89&#8243; background_layout=\u00bblight\u00bb]<\/p>\n<p>[Best_Wordpress_Gallery id=\u00bb39&#8243; gal_title=\u00bbPresentaci\u00f3n reliquia Don Bosco\u00bb]<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestro sacerdote Don Fidel ha presentado hoy la reliquia de Don Bosco que tenemos en el colegio a nuestros alumnos de primero de ciclos formativos, destacando tambi\u00e9n algunos aspectos llamativos de su vida. Esta tutor\u00eda es una de las actividades que se est\u00e1n llevando a cabo con motivo de la Festividad del Mes de Don [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[16,19,21],"tags":[],"class_list":["post-4164","post","type-post","status-publish","format-standard","hentry","category-casa","category-familia-salesiana","category-familiasalesiana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentaci\u00f3n reliquias de Don Bosco - Familia Salesiana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentaci\u00f3n reliquias de Don Bosco - Familia Salesiana\" \/>\n<meta property=\"og:description\" content=\"Nuestro sacerdote Don Fidel ha presentado hoy la reliquia de Don Bosco que tenemos en el colegio a nuestros alumnos de primero de ciclos formativos, destacando tambi\u00e9n algunos aspectos llamativos de su vida. Esta tutor\u00eda es una de las actividades que se est\u00e1n llevando a cabo con motivo de la Festividad del Mes de Don [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/\" \/>\n<meta property=\"og:site_name\" content=\"Familia Salesiana\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-18T11:30:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-26T11:36:36+00:00\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/blog\\\/2018\\\/01\\\/18\\\/presentacion-reliquias-de-don-bosco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/blog\\\/2018\\\/01\\\/18\\\/presentacion-reliquias-de-don-bosco\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/97b196c36a3b0e81b5396dcd01e791a7\"},\"headline\":\"Presentaci\u00f3n reliquias de Don Bosco\",\"datePublished\":\"2018-01-18T11:30:14+00:00\",\"dateModified\":\"2018-01-26T11:36:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/blog\\\/2018\\\/01\\\/18\\\/presentacion-reliquias-de-don-bosco\\\/\"},\"wordCount\":271,\"commentCount\":0,\"articleSection\":[\"Casa\",\"Familia Salesiana\",\"FamiliaSalesiana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/blog\\\/2018\\\/01\\\/18\\\/presentacion-reliquias-de-don-bosco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/blog\\\/2018\\\/01\\\/18\\\/presentacion-reliquias-de-don-bosco\\\/\",\"url\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/blog\\\/2018\\\/01\\\/18\\\/presentacion-reliquias-de-don-bosco\\\/\",\"name\":\"Presentaci\u00f3n reliquias de Don Bosco - Familia Salesiana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/#website\"},\"datePublished\":\"2018-01-18T11:30:14+00:00\",\"dateModified\":\"2018-01-26T11:36:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/97b196c36a3b0e81b5396dcd01e791a7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/blog\\\/2018\\\/01\\\/18\\\/presentacion-reliquias-de-don-bosco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/blog\\\/2018\\\/01\\\/18\\\/presentacion-reliquias-de-don-bosco\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/blog\\\/2018\\\/01\\\/18\\\/presentacion-reliquias-de-don-bosco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentaci\u00f3n reliquias de Don Bosco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/#website\",\"url\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/\",\"name\":\"Familia Salesiana\",\"description\":\"P\u00e1gina oficial Salesianos Palma del R\u00edo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/palmadelrio.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/97b196c36a3b0e81b5396dcd01e791a7\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5ea960238184b4a6866cff40655528c87f1cd121f97989875982221474c9a9e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5ea960238184b4a6866cff40655528c87f1cd121f97989875982221474c9a9e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5ea960238184b4a6866cff40655528c87f1cd121f97989875982221474c9a9e?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentaci\u00f3n reliquias de Don Bosco - Familia Salesiana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/","og_locale":"es_ES","og_type":"article","og_title":"Presentaci\u00f3n reliquias de Don Bosco - Familia Salesiana","og_description":"Nuestro sacerdote Don Fidel ha presentado hoy la reliquia de Don Bosco que tenemos en el colegio a nuestros alumnos de primero de ciclos formativos, destacando tambi\u00e9n algunos aspectos llamativos de su vida. Esta tutor\u00eda es una de las actividades que se est\u00e1n llevando a cabo con motivo de la Festividad del Mes de Don [&hellip;]","og_url":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/","og_site_name":"Familia Salesiana","article_published_time":"2018-01-18T11:30:14+00:00","article_modified_time":"2018-01-26T11:36:36+00:00","author":"Gestor Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gestor Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/#article","isPartOf":{"@id":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/"},"author":{"name":"Gestor Web","@id":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/#\/schema\/person\/97b196c36a3b0e81b5396dcd01e791a7"},"headline":"Presentaci\u00f3n reliquias de Don Bosco","datePublished":"2018-01-18T11:30:14+00:00","dateModified":"2018-01-26T11:36:36+00:00","mainEntityOfPage":{"@id":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/"},"wordCount":271,"commentCount":0,"articleSection":["Casa","Familia Salesiana","FamiliaSalesiana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/","url":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/","name":"Presentaci\u00f3n reliquias de Don Bosco - Familia Salesiana","isPartOf":{"@id":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/#website"},"datePublished":"2018-01-18T11:30:14+00:00","dateModified":"2018-01-26T11:36:36+00:00","author":{"@id":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/#\/schema\/person\/97b196c36a3b0e81b5396dcd01e791a7"},"breadcrumb":{"@id":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/blog\/2018\/01\/18\/presentacion-reliquias-de-don-bosco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/"},{"@type":"ListItem","position":2,"name":"Presentaci\u00f3n reliquias de Don Bosco"}]},{"@type":"WebSite","@id":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/#website","url":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/","name":"Familia Salesiana","description":"P\u00e1gina oficial Salesianos Palma del R\u00edo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/#\/schema\/person\/97b196c36a3b0e81b5396dcd01e791a7","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b5ea960238184b4a6866cff40655528c87f1cd121f97989875982221474c9a9e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b5ea960238184b4a6866cff40655528c87f1cd121f97989875982221474c9a9e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b5ea960238184b4a6866cff40655528c87f1cd121f97989875982221474c9a9e?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/4164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/comments?post=4164"}],"version-history":[{"count":1,"href":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/4164\/revisions"}],"predecessor-version":[{"id":4166,"href":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/4164\/revisions\/4166"}],"wp:attachment":[{"href":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/media?parent=4164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/categories?post=4164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palmadelrio.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/tags?post=4164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}